{"id":991,"date":"2026-02-01T22:28:15","date_gmt":"2026-02-01T22:28:15","guid":{"rendered":"https:\/\/casachangomexico.com\/?page_id=991"},"modified":"2026-06-09T23:06:19","modified_gmt":"2026-06-09T23:06:19","slug":"get-away-retreat-casa-chango-mexico","status":"publish","type":"page","link":"https:\/\/casachangomexico.com\/es\/get-away-retreat-casa-chango-mexico\/","title":{"rendered":"Esc\u00e1pate! Retiro Casa Chango M\u00e9xico"},"content":{"rendered":"<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.588), 25px);\"><strong>Date una Escapada<\/strong><\/h1>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">en <a href=\"https:\/\/sweetretreatsmexico.com\/casa-chango-mexico-retreat-center\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em><strong>Casa Chango <\/strong>Mexico<\/em><\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>\u00a1Individuos, parejas, familias y grupos de amigos!<\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Disponible todo el a\u00f1o<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n\n\n<div class=\"aligncenter wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/sweetretreatsmexico.secure.retreat.guru\/program\/get-away-retreat-casa-chango-mexico\/?form=1&amp;lang=en\" target=\"_blank\" rel=\"noreferrer noopener\">INSCR\u00cdBEME<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"is-style-wide wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-black-color has-text-color has-text-align-center has-large-font-size wp-block-paragraph\">\u00bfC\u00f3mo es un <strong>Esc\u00e1pate!<\/strong> <strong>Retiro<\/strong> en <a href=\"https:\/\/sweetretreatsmexico.com\/casa-chango-finca-del-artes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Casa Chango<\/a>?<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Imag\u00ednate en M\u00e9xico en un eco-resort todo incluido que fue co-creado por so\u00f1adores, artistas y artistas de circo.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Puede hacer ejercicio, jugar y bailar en nuestro gimnasio de circo al aire libre o estudio de baile\/yoga, sal\u00f3n junto a la piscina y jacuzzi y estar totalmente apoyado con 3 comidas equilibradas y saludables al d\u00eda.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Estar\u00e1s expuesto a todas las cosas maravillosas que nuestra casa en Puerto Escondido, M\u00e9xico, tiene para ofrecer. Rel\u00e1jate junto a la piscina o en una hamaca. Disfruta de viajes a la playa, excursiones por la naturaleza, caminatas por el r\u00edo, masajes y m\u00e1s. Se le apoyar\u00e1 para crear la experiencia que desea y necesita.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Todos son bienvenidos. Amigos, familias, hijos, etc. \u00a1Ven solo o trae a tu tripulaci\u00f3n!<\/p>\n\n\n\n<div class=\"wp-block-cover\" style=\"min-height:536px;aspect-ratio:unset;\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-block-cover__image-background wp-image-14928\" alt=\"\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/05\/Hammocks-above-and-below-Rober-scaled.jpg?ssl=1\" style=\"object-position:48% 16%\" data-object-fit=\"cover\" data-object-position=\"48% 16%\"\/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-black-color has-text-color has-text-align-center wp-block-paragraph\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.497), 22px);\"><strong>Qu\u00e9 incluye: <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><strong>Alojamiento privado o compartido en nuestro nuevo resort ecol\u00f3gico.<\/strong> <a href=\"https:\/\/sweetretreatsmexico.com\/casa-chango-mexico-accommodations\/\" target=\"_blank\" rel=\"noreferrer noopener\">Haz clic aqu\u00ed<\/a> para ver sus opciones. <\/li>\n\n\n\n<li class=\"\"><strong>Servicio de limpieza diario. <\/strong><\/li>\n\n\n\n<li class=\"\"><strong>Traslado al aeropuerto<\/strong> desde el aeropuerto de Puerto Escondido (PXM) a Casa Chango.<\/li>\n\n\n\n<li class=\"\"><strong>3 comidas nutritivas al d\u00eda en nuestra hermosa cocina abierta.<\/strong> <a href=\"https:\/\/sweetretreatsmexico.com\/meals\/\" target=\"_blank\" rel=\"noreferrer noopener\">Haz clic aqu\u00ed<\/a> para saber m\u00e1s sobre las comidas.\n<ul class=\"wp-block-list\">\n<li class=\"\">Nota: Habr\u00e1 un d\u00eda en el que las comidas ser\u00e1n limitadas. Recomendamos explorar restaurantes locales.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li class=\"\"><strong>Uso de todas las \u00e1reas comunitarias:<\/strong>\n<ul class=\"wp-block-list\">\n<li class=\"\">Piscina y jacuzzi <\/li>\n\n\n\n<li class=\"\">Cocina y comedor, \u00e1rea de sal\u00f3n con sof\u00e1s, libros y juegos<\/li>\n\n\n\n<li class=\"\">Gimnasio al aire libre con equipamieo de circo<\/li>\n\n\n\n<li class=\"\">Estudio de Danza<\/li>\n\n\n\n<li class=\"\">Hamacas <\/li>\n\n\n\n<li class=\"\">Sendero privado hasta el r\u00edo Colotepec<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li class=\"\"><strong>2 Viajes a la Playa<\/strong><\/li>\n\n\n\n<li class=\"\"><strong>Viaje a un mercado local<\/strong><\/li>\n\n\n\n<li class=\"\"><strong>Internet Starlink de alta velocidad:<\/strong> Starlink proporciona acceso a Internet de alta velocidad y baja latencia a personas de todo el mundo, especialmente a aquellas en \u00e1reas rurales y remotas que actualmente carecen de acceso a Internet confiable. <\/li>\n\n\n\n<li class=\"\"><strong>Acceso a<\/strong> nuestra red de profesores de espa\u00f1ol que imparten clases particulares o grupales presenciales.<\/li>\n\n\n\n<li class=\"\"><strong>Acceso a<\/strong> nuestro espacio de masajes en el lugar y a una red de profesionales de terapeutas para contratar que vienen al lugar. <\/li>\n\n\n\n<li class=\"\"><strong>Recomendaciones y consejos<\/strong> para disfrutar de todo lo que Puerto Escondido ofrece. Playas, excursiones por la naturaleza, tours, clases de surf, eventos de networking, clases de baile y mucho m\u00e1s.  <a href=\"https:\/\/sweetretreatsmexico.com\/excursions-adventures\/\" target=\"_blank\" rel=\"noreferrer noopener\">Haz clic aqu\u00ed<\/a> para tener una idea de lo que te espera.   <\/li>\n<\/ul>\n\n\n\n<p class=\"has-black-color has-text-color has-text-align-center wp-block-paragraph\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.497), 22px);\"><strong>No incluido:<\/strong>: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><strong>Transporte <\/strong>\n<ul class=\"wp-block-list\">\n<li class=\"\"><a href=\"https:\/\/sweetretreatsmexico.com\/your-trip-to-mexico\/\" target=\"_blank\" rel=\"noreferrer noopener\">Haz clic aqu\u00ed<\/a> para obtener consejos de viaje y recomendaciones sobre c\u00f3mo reservar vuelos.<\/li>\n\n\n\n<li class=\"\">Hay taxis, colectivos, alquiler de motos y coches disponibles a nivel local que facilitan la exploraci\u00f3n. <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li class=\"\">Masajes, clases de espa\u00f1ol y otras excursiones se reservan por separado y directamente con los proveedores seg\u00fan sea necesario.<\/li>\n\n\n\n<li class=\"\"><strong>Classes <\/strong>&#8211; Group or Private Classes are available at an additional rate.\n<ul class=\"wp-block-list\">\n<li class=\"\">Yoga, Fitness, Conditioning, Aerial\/Acrobatics, Core Strength, Somatic Functional Fitness, Creative Movement<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-cover is-light\" style=\"min-height:450px;aspect-ratio:unset;\"><img data-recalc-dims=\"1\" height=\"1024\" width=\"1024\" decoding=\"async\" class=\"wp-block-cover__image-background wp-image-21412 size-large\" alt=\"\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2025\/11\/yoga-class-meditation-940x515.jpeg?fit=1024%2C1024&#038;ssl=1\" data-object-fit=\"cover\"\/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#af9d6b\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Precios del retiro (por persona):<\/h2>\n\n\n\n<figure class=\"has-fixed-layout is-style-stripes wp-block-table\"><table><tbody><tr><td>Habitaci\u00f3n <\/td><td>Nightly<\/td><td>1 week<\/td><td>2 weeks<\/td><td>3 weeks<\/td><\/tr><tr><td>Dormitorio compartido (mixto)<\/td><td>$178<\/td><td>$1250<\/td><td>$2400<\/td><td>$3000<\/td><\/tr><tr><td>Habitaci\u00f3n privada con ocupaci\u00f3n doble con ba\u00f1o compartido 2 amigos compartiendo habitaci\u00f3n<\/td><td>$195<\/td><td>$1350<\/td><td>$2500<\/td><td>$3100<\/td><\/tr><tr><td>Habitaci\u00f3n privada con ocupaci\u00f3n doble con ba\u00f1o privado para 2 amigos compartiendo habitaci\u00f3n<\/td><td>$215<\/td><td>$1500<\/td><td>$2650<\/td><td>$3200<\/td><\/tr><tr><td>Habitaci\u00f3n privada con ba\u00f1o compartido<\/td><td>$258<\/td><td>$1800<\/td><td>$3200<\/td><td>$4000<\/td><\/tr><tr><td>Habitaci\u00f3n privada con ba\u00f1o privado<\/td><td>$285<\/td><td>$2000<\/td><td>$3500<\/td><td>$4800<\/td><\/tr><tr><td>Habitaci\u00f3n privada con ba\u00f1o privado y aire acondicionado<\/td><td>$328<\/td><td>$2300<\/td><td>$4000<\/td><td>$5400<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Los precios son por persona en USD.<br>Se requiere un dep\u00f3sito de $500 USD para reservar su lugar.&nbsp;<br>La matr\u00edcula completa vence 30 d\u00edas antes de la llegada.<br>Las tarifas se refieren al costo de la matr\u00edcula semanal para una persona.<br>Los amigos que comparten una habitaci\u00f3n deben inscribirse juntos.<br>Precios especiales para parejas.<br>Los dormitorios son mixtos.<br><a href=\"https:\/\/sweetretreatsmexico.com\/casa-chango-mexico-accommodations\/\">Haz clic aqu\u00ed<\/a>&nbsp;para ver las descripciones de las habitaciones.<\/figcaption><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\" style=\"font-size:10px\">Open Gym Train-cation Retreat Mexico Open Gym Train-cation Retreat Mexico Open Gym Train-cation Retreat Mexico Open Gym Train-cation Retreat Mexico<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"aligncenter wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/sweetretreatsmexico.secure.retreat.guru\/program\/get-away-retreat-casa-chango-mexico\/?form=1&amp;lang=en\" target=\"_blank\" rel=\"noreferrer noopener\">INSCR\u00cdBEME<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/08\/Jacuzzi-3-crop-scaled.jpg?ssl=1\"><img data-recalc-dims=\"1\" height=\"545\" width=\"940\" decoding=\"async\" data-id=\"16218\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/08\/Jacuzzi-3-crop-940x545.jpg?resize=940%2C545&#038;ssl=1\" alt=\"\" class=\"wp-image-16218\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/10\/jacuzzi-deborah-papaya.png?ssl=1\"><img data-recalc-dims=\"1\" height=\"454\" width=\"940\" decoding=\"async\" data-id=\"16451\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/10\/jacuzzi-deborah-papaya-940x454.png?resize=940%2C454&#038;ssl=1\" alt=\"\" class=\"wp-image-16451\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/pool-edge-Sarita-scaled.jpeg?ssl=1\"><img data-recalc-dims=\"1\" height=\"627\" width=\"940\" decoding=\"async\" data-id=\"21765\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/pool-edge-Sarita-940x627.jpeg?resize=940%2C627&#038;ssl=1\" alt=\"\" class=\"wp-image-21765\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/pool-swing-soak-scaled.jpeg?ssl=1\"><img data-recalc-dims=\"1\" height=\"940\" width=\"940\" decoding=\"async\" data-id=\"21766\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/pool-swing-soak-940x940.jpeg?resize=940%2C940&#038;ssl=1\" alt=\"\" class=\"wp-image-21766\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/buddah-bowl-close-scaled.jpeg?ssl=1\"><img data-recalc-dims=\"1\" height=\"627\" width=\"940\" decoding=\"async\" data-id=\"21767\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/buddah-bowl-close-940x627.jpeg?resize=940%2C627&#038;ssl=1\" alt=\"\" class=\"wp-image-21767\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/Lunch-2025-scaled.jpeg?ssl=1\"><img data-recalc-dims=\"1\" height=\"627\" width=\"940\" decoding=\"async\" data-id=\"21768\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/Lunch-2025-940x627.jpeg?resize=940%2C627&#038;ssl=1\" alt=\"\" class=\"wp-image-21768\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/Gym-eve-corner-2025-scaled.jpeg?ssl=1\"><img data-recalc-dims=\"1\" height=\"627\" width=\"940\" decoding=\"async\" data-id=\"21769\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/Gym-eve-corner-2025-940x627.jpeg?resize=940%2C627&#038;ssl=1\" alt=\"\" class=\"wp-image-21769\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/choco-cake-and-ice-coffee-scaled.jpeg?ssl=1\"><img data-recalc-dims=\"1\" height=\"627\" width=\"940\" decoding=\"async\" data-id=\"21770\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/choco-cake-and-ice-coffee-940x627.jpeg?resize=940%2C627&#038;ssl=1\" alt=\"\" class=\"wp-image-21770\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/11\/Gym-Empty-aug-2023-crop-scaled.jpg?ssl=1\"><img data-recalc-dims=\"1\" height=\"473\" width=\"940\" decoding=\"async\" data-id=\"16728\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/11\/Gym-Empty-aug-2023-crop-940x473.jpg?resize=940%2C473&#038;ssl=1\" alt=\"\" class=\"wp-image-16728\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/01\/sunset-gym-group-copy-scaled.jpg?ssl=1\"><img data-recalc-dims=\"1\" height=\"828\" width=\"940\" decoding=\"async\" data-id=\"14112\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/01\/sunset-gym-group-copy-940x828.jpg?resize=940%2C828&#038;ssl=1\" alt=\"\" class=\"wp-image-14112\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/04\/hammock-pool.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" data-id=\"14794\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/04\/hammock-pool.jpg?ssl=1\" alt=\"\" class=\"wp-image-14794\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/Natalie-hammock-ukelele-Rober-scaled.jpg?ssl=1\"><img data-recalc-dims=\"1\" height=\"628\" width=\"940\" decoding=\"async\" data-id=\"21771\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2026\/02\/Natalie-hammock-ukelele-Rober-940x628.jpg?resize=940%2C628&#038;ssl=1\" alt=\"\" class=\"wp-image-21771\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2025\/11\/ECSTATIC-circle-copy-scaled.jpeg?ssl=1\"><img data-recalc-dims=\"1\" height=\"628\" width=\"940\" decoding=\"async\" data-id=\"21429\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2025\/11\/ECSTATIC-circle-copy-940x628.jpeg?resize=940%2C628&#038;ssl=1\" alt=\"\" class=\"wp-image-21429\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/05\/hairflip-4-people-1-scaled.jpeg?ssl=1\"><img data-recalc-dims=\"1\" height=\"705\" width=\"940\" decoding=\"async\" data-id=\"15109\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/05\/hairflip-4-people-1-940x705.jpeg?resize=940%2C705&#038;ssl=1\" alt=\"\" class=\"wp-image-15109\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2022\/06\/turtle.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" data-id=\"13352\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2022\/06\/turtle.jpg?ssl=1\" alt=\"\" class=\"wp-image-13352\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/06\/acro-yoga-beach-2.jpg?ssl=1\"><img data-recalc-dims=\"1\" height=\"529\" width=\"940\" decoding=\"async\" data-id=\"15426\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/06\/acro-yoga-beach-2-940x529.jpg?resize=940%2C529&#038;ssl=1\" alt=\"\" class=\"wp-image-15426\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/08\/sunset-Casa-Chango-Stu-crop.jpg?ssl=1\"><img data-recalc-dims=\"1\" height=\"613\" width=\"940\" decoding=\"async\" data-id=\"16118\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/08\/sunset-Casa-Chango-Stu-crop-940x613.jpg?resize=940%2C613&#038;ssl=1\" alt=\"\" class=\"wp-image-16118\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/08\/heart-hands-sunset-crop-scaled.jpg?ssl=1\"><img data-recalc-dims=\"1\" height=\"529\" width=\"940\" decoding=\"async\" data-id=\"16066\" src=\"https:\/\/i0.wp.com\/sweetretreatsmexico.com\/wp-content\/uploads\/2023\/08\/heart-hands-sunset-crop-940x529.jpg?resize=940%2C529&#038;ssl=1\" alt=\"\" class=\"wp-image-16066\"\/><\/a><\/figure>\n<\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"block-e9152661-b237-401b-b842-fd0f4d5f5b43\">Enlaces para m\u00e1s informaci\u00f3n: <\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><a href=\"https:\/\/sweetretreatsmexico.com\/mexico-accommodations\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<\/a><a href=\"https:\/\/sweetretreatsmexico.com\/casa-chango-mexico-accommodations\/\" target=\"_blank\" rel=\"noreferrer noopener\">Alojamiento<\/a><\/li>\n\n\n\n<li class=\"\"><a href=\"https:\/\/sweetretreatsmexico.com\/meals\/\" target=\"_blank\" rel=\"noreferrer noopener\">Alimentos<\/a><\/li>\n\n\n\n<li class=\"\"><a href=\"https:\/\/sweetretreatsmexico.com\/your-trip-to-mexico\/\" target=\"_blank\" rel=\"noreferrer noopener\">Como llegar aqu\u00ed y otros consejos de viaje.<\/a><\/li>\n\n\n\n<li class=\"\"><a href=\"https:\/\/weatherspark.com\/y\/7293\/Average-Weather-in-Puerto-Escondido-Mexico-Year-Round\" target=\"_blank\" rel=\"noreferrer noopener\">El clima en Puerto Escondido<\/a><\/li>\n\n\n\n<li class=\"\"><a href=\"https:\/\/sweetretreatsmexico.com\/testimonials\/\" target=\"_blank\" rel=\"noreferrer noopener\">Testimonios<\/a><\/li>\n\n\n\n<li class=\"\"><a href=\"https:\/\/casachangomexico.com\/es\/excursions\/\" target=\"_blank\" rel=\"noreferrer noopener\">Excursiones<\/a><\/li>\n\n\n\n<li class=\"\"><a href=\"https:\/\/www.instagram.com\/sweetretreatsmx\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram <\/a><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h6 class=\"wp-block-heading\">&nbsp;<\/h6>\n\n\n\n<h5 class=\"wp-block-heading has-text-align-center\" id=\"block-b74a3d37-b724-47d7-a240-a036b9dddf50\" style=\"font-size:10px\"><em><br>Pol\u00edtica de cancelaci\u00f3n: <\/em>No se realizan reembolsos. Sin excepciones.<br><em>Sin reembolsos.&nbsp;<\/em><br><em>Los dep\u00f3sitos no son reembolsables ni transferibles.<\/em><br><em>Cancelaci\u00f3n con m\u00e1s de 60 d\u00edas de antelaci\u00f3n al primer d\u00eda del retiro: el 50% de la matr\u00edcula pagada se puede transferir a un futuro Sweet Retreat dentro de los 18 meses posteriores a la cancelaci\u00f3n.<\/em><br><em>Cancelaci\u00f3n entre 30 y 60 d\u00edas antes del primer d\u00eda del retiro: el 25% de la matr\u00edcula pagada se puede transferir a un futuro Sweet Retreat dentro de los 18 meses posteriores a la cancelaci\u00f3n.<\/em><br><em>Las cancelaciones hasta 30 d\u00edas antes del primer d\u00eda del retiro no se acreditar\u00e1n ni reembolsar\u00e1n por ning\u00fan motivo.&nbsp;<\/em><br><em>Al momento de pagar tu retiro, te recomendamos  que adquieras una p\u00f3liza de seguro de viaje. Aseg\u00farate de que tu p\u00f3liza cubra el costo total de la tarifa del retiro, as\u00ed como cancelaciones inesperadas, retrasos en el viaje, p\u00e9rdidas y otros riesgos. Adem\u00e1s, considera la protecci\u00f3n por vuelos cancelados o retrasados, p\u00e9rdida de equipaje y necesidades m\u00e9dicas durante el viaje. Por favor, trae la p\u00f3liza contigo en caso de emergencia. <\/em><a href=\"https:\/\/www.imglobal.com\/img-producer-insurance-plans\"><em>Haz clic aqu\u00ed para obtener informaci\u00f3n sobre IM Global Insurance.<\/em><\/a>&nbsp; <a href=\"https:\/\/www.gowanderwell.com\/\"><em>Haz clic aqu\u00ed para obtener informaci\u00f3n sobre WanderWell Insurance.<\/em><\/a>&nbsp;<br><a href=\"https:\/\/sweetretreatsmexico.com\/terms-conditions\/\">Consulta la lista completa de t\u00e9rminos y condiciones aqu\u00ed.<\/a><br><a href=\"https:\/\/sweetretreatsmexico.com\/covid-policy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vea la pol\u00edtica completa de COVID aqu\u00ed.<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Get Away Retreat at Casa Chango Mexico Individuals, couples, families, and groups of friends! Available Year Round What does a Get Away Retreat at Casa Chango look like? Imagine yourself in Mexico at an all-inclusive eco-resort that was co-created by dreamers, artists &amp; circus performers. You can exercise, play, and dance in our open-air circus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":997,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-991","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Get Away Retreat Casa Chango Mexico - Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casachangomexico.com\/es\/get-away-retreat-casa-chango-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Get Away Retreat Casa Chango Mexico - Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature\" \/>\n<meta property=\"og:description\" content=\"Get Away Retreat at Casa Chango Mexico Individuals, couples, families, and groups of friends! Available Year Round What does a Get Away Retreat at Casa Chango look like? Imagine yourself in Mexico at an all-inclusive eco-resort that was co-created by dreamers, artists &amp; circus performers. You can exercise, play, and dance in our open-air circus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casachangomexico.com\/es\/get-away-retreat-casa-chango-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CasaChangoMexico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T23:06:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casachangomexico.com\/wp-content\/uploads\/2026\/02\/Get-Away-Retreat-Banner-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casachangomexico.com\\\/get-away-retreat-casa-chango-mexico\\\/\",\"url\":\"https:\\\/\\\/casachangomexico.com\\\/get-away-retreat-casa-chango-mexico\\\/\",\"name\":\"Get Away Retreat Casa Chango Mexico - Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casachangomexico.com\\\/get-away-retreat-casa-chango-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casachangomexico.com\\\/get-away-retreat-casa-chango-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casachangomexico.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Get-Away-Retreat-Banner-2.jpg?fit=1640%2C924&ssl=1\",\"datePublished\":\"2026-02-01T22:28:15+00:00\",\"dateModified\":\"2026-06-09T23:06:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casachangomexico.com\\\/get-away-retreat-casa-chango-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casachangomexico.com\\\/get-away-retreat-casa-chango-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casachangomexico.com\\\/get-away-retreat-casa-chango-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casachangomexico.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Get-Away-Retreat-Banner-2.jpg?fit=1640%2C924&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casachangomexico.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Get-Away-Retreat-Banner-2.jpg?fit=1640%2C924&ssl=1\",\"width\":1640,\"height\":924},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casachangomexico.com\\\/get-away-retreat-casa-chango-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casachangomexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Get Away Retreat Casa Chango Mexico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/#website\",\"url\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/\",\"name\":\"Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature\",\"description\":\"Extraordinary setting for anyone who wants to relax, play, practice movement, create, explore, rediscover themselves &amp; connect with nature. \\n\",\"publisher\":{\"@id\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/#organization\",\"name\":\"Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature\",\"url\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casachangomexico.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Casa-Chango-Logo-w-leaves-2024-no-background-1.png?fit=517%2C279&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casachangomexico.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Casa-Chango-Logo-w-leaves-2024-no-background-1.png?fit=517%2C279&ssl=1\",\"width\":517,\"height\":279,\"caption\":\"Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature\"},\"image\":{\"@id\":\"https:\\\/\\\/ohw.fmn.mybluehost.me\\\/casachangomexico\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaChangoMexico\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Get Away Retreat Casa Chango Mexico - Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casachangomexico.com\/es\/get-away-retreat-casa-chango-mexico\/","og_locale":"es_MX","og_type":"article","og_title":"Get Away Retreat Casa Chango Mexico - Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature","og_description":"Get Away Retreat at Casa Chango Mexico Individuals, couples, families, and groups of friends! Available Year Round What does a Get Away Retreat at Casa Chango look like? Imagine yourself in Mexico at an all-inclusive eco-resort that was co-created by dreamers, artists &amp; circus performers. You can exercise, play, and dance in our open-air circus [&hellip;]","og_url":"https:\/\/casachangomexico.com\/es\/get-away-retreat-casa-chango-mexico\/","og_site_name":"Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature","article_publisher":"https:\/\/www.facebook.com\/CasaChangoMexico","article_modified_time":"2026-06-09T23:06:19+00:00","og_image":[{"width":1640,"height":924,"url":"https:\/\/casachangomexico.com\/wp-content\/uploads\/2026\/02\/Get-Away-Retreat-Banner-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casachangomexico.com\/get-away-retreat-casa-chango-mexico\/","url":"https:\/\/casachangomexico.com\/get-away-retreat-casa-chango-mexico\/","name":"Get Away Retreat Casa Chango Mexico - Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature","isPartOf":{"@id":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casachangomexico.com\/get-away-retreat-casa-chango-mexico\/#primaryimage"},"image":{"@id":"https:\/\/casachangomexico.com\/get-away-retreat-casa-chango-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casachangomexico.com\/wp-content\/uploads\/2026\/02\/Get-Away-Retreat-Banner-2.jpg?fit=1640%2C924&ssl=1","datePublished":"2026-02-01T22:28:15+00:00","dateModified":"2026-06-09T23:06:19+00:00","breadcrumb":{"@id":"https:\/\/casachangomexico.com\/get-away-retreat-casa-chango-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casachangomexico.com\/get-away-retreat-casa-chango-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casachangomexico.com\/get-away-retreat-casa-chango-mexico\/#primaryimage","url":"https:\/\/i0.wp.com\/casachangomexico.com\/wp-content\/uploads\/2026\/02\/Get-Away-Retreat-Banner-2.jpg?fit=1640%2C924&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casachangomexico.com\/wp-content\/uploads\/2026\/02\/Get-Away-Retreat-Banner-2.jpg?fit=1640%2C924&ssl=1","width":1640,"height":924},{"@type":"BreadcrumbList","@id":"https:\/\/casachangomexico.com\/get-away-retreat-casa-chango-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casachangomexico.com\/"},{"@type":"ListItem","position":2,"name":"Get Away Retreat Casa Chango Mexico"}]},{"@type":"WebSite","@id":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/#website","url":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/","name":"Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature","description":"Extraordinary setting for anyone who wants to relax, play, practice movement, create, explore, rediscover themselves &amp; connect with nature.","publisher":{"@id":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/#organization","name":"Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature","url":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casachangomexico.com\/wp-content\/uploads\/2024\/09\/Casa-Chango-Logo-w-leaves-2024-no-background-1.png?fit=517%2C279&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casachangomexico.com\/wp-content\/uploads\/2024\/09\/Casa-Chango-Logo-w-leaves-2024-no-background-1.png?fit=517%2C279&ssl=1","width":517,"height":279,"caption":"Casa Chango Mexico eco-chic retreat center creativity &amp; connection with nature"},"image":{"@id":"https:\/\/ohw.fmn.mybluehost.me\/casachangomexico\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaChangoMexico"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/pages\/991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/comments?post=991"}],"version-history":[{"count":5,"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/pages\/991\/revisions"}],"predecessor-version":[{"id":1176,"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/pages\/991\/revisions\/1176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/media\/997"}],"wp:attachment":[{"href":"https:\/\/casachangomexico.com\/es\/wp-json\/wp\/v2\/media?parent=991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}